{"id":3710,"date":"2025-01-31T11:31:49","date_gmt":"2025-01-31T11:31:49","guid":{"rendered":"https:\/\/snoeck.process-vision.de\/shop\/sigmar-polke-plakate\/"},"modified":"2026-04-08T14:25:31","modified_gmt":"2026-04-08T13:25:31","slug":"sigmar-polke-plakate","status":"publish","type":"product","link":"https:\/\/snoeck.de\/fr\/shop\/sigmar-polke-plakate\/","title":{"rendered":"Affiches de Sigmar Polke"},"content":{"rendered":"<h3>Les affiches Polke dans la collection Ciesilski<\/h3>\n<p>Axel Ciesielski est un collectionneur passionn\u00e9 des \u0153uvres de Sigmar Polke et probablement le seul au monde \u00e0 poss\u00e9der l'int\u00e9gralit\u00e9 des \u00e9ditions de l'artiste. Elles sont actuellement expos\u00e9es \u00e0 Siegen au Museum f\u00fcr Gegenwartskunst et le seront \u00e0 partir du printemps 2014 aux Abattoirs de Toulouse. L'intense activit\u00e9 de collectionneur d'Axel Ciesielski se base bien s\u00fbr sur une solide collection de nombreux dessins et toiles, m\u00eame anciens, mais comprend \u00e9galement depuis toujours les affiches des expositions. Le pr\u00e9sent volume reproduit donc pour la premi\u00e8re fois l'int\u00e9gralit\u00e9 des affiches \u00e9dit\u00e9es \u00e0 ce jour pour des expositions consacr\u00e9es \u00e0 des \u0153uvres de Sigmar Polke - des affiches qui sont presque sans exception d\u00e9termin\u00e9es par un regard ironique qui renvoie \u00e0 l'esprit anarchique et \u00e0 l'univers formellement novateur de cet artiste hors du commun. Mais la particularit\u00e9 de cette collection d'affiches, \u00e9crit Claus von der Osten, \u00e9diteur du catalogue raisonn\u00e9 des \u00e9ditions, dans son texte d'introduction, r\u00e9side surtout dans le fait que le collectionneur a sauvegard\u00e9 dans une qualit\u00e9 irr\u00e9prochable toutes les affiches que l'artiste a lui-m\u00eame inscrites dans le catalogue raisonn\u00e9 des \u00e9ditions en tant qu'affiches d'artiste. Mais le volume est aussi un voyage dans le temps \u00e0 travers le monde de l'art depuis les ann\u00e9es 1960. En le feuilletant, on se rend vite compte o\u00f9 et par qui les d\u00e9buts de Polke ont \u00e9t\u00e9 accompagn\u00e9s et o\u00f9 des pr\u00e9sentations ont eu lieu par la suite, mais aussi quelles grandes expositions institutionnelles (r\u00e9trospectives) ont favoris\u00e9 et refl\u00e9t\u00e9 la renomm\u00e9e mondiale de l'artiste. Cet ouvrage est donc un who's who de l'art contemporain, qu'il soit pr\u00e9sent\u00e9 par des galeries, des associations artistiques ou des mus\u00e9es de renomm\u00e9e mondiale. Il ne s'agit pas seulement de motifs connus de l'artiste, mais aussi de motifs \u00e9nigmatiques, ce qui fait de ce volume un aper\u00e7u des diff\u00e9rentes facettes de l'\u0153uvre de l'artiste.<\/p>","protected":false},"excerpt":{"rendered":"<p>Textes (all.\/ang.) d'Axel Ciesielski, Claus von der Osten<br \/>\n328 p. avec 170 illustrations en couleur<br \/>\nformat 28,5 x 24 cm, couverture rigide<\/p>","protected":false},"featured_media":5125,"template":"","meta":[],"product_brand":[],"product_cat":[95],"product_tag":[],"class_list":{"0":"post-3710","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vergriffen","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"product-type-simple"},"aioseo_notices":[],"_wp_attached_file":null,"_wp_attachment_metadata":null,"_wc_attachment_source":null,"_elementor_inline_svg":null,"_elementor_is_screenshot":null,"_elementor_source_image_hash":null,"_source_url":null,"_wp_attachment_context":null,"_menu_item_type":null,"_menu_item_menu_item_parent":null,"_menu_item_object_id":null,"_menu_item_object":null,"_menu_item_target":null,"_menu_item_classes":null,"_menu_item_xfn":null,"_menu_item_url":null,"__elementor_forms_snapshot":null,"_unit":"","_unit_base":"","_unit_product":"","_unit_price_auto":"no","_unit_price_regular":"","_unit_price":"","_unit_price_sale":"","_sale_price_label":"","_sale_price_regular_label":"","_manufacturer_slug":"","_mini_desc":"","_defect_description":"","_safety_instructions":"","_allergen_ids":[],"_warranty_attachment_id":"","_safety_attachment_ids":[],"_min_age":"","_ts_gtin":"","_ts_mpn":"","_delivery_time_countries":[],"_free_shipping":"no","_service":"no","_photovoltaic_system":"no","_used_good":"no","_defective_copy":"no","_wireless_electronic_device":"no","_device_contains_power_supply":"no","_device_charging_supports_usb_pd":"no","_device_charging_watt_min":"0","_device_charging_watt_max":"0","_is_food":"no","_differential_taxation":"no","_gzd_version":"3.18.7","_hs_code":"","_customs_description":"","_manufacture_country":"0","_is_non_returnable":"no","_shipping_length":"","_shipping_width":"","_shipping_height":"","_sku":"ISBN 978-3-86442-054-2","_global_unique_id":"978-3-86442-054-2","_regular_price":null,"total_sales":"0","_tax_status":"taxable","_tax_class":"","_manage_stock":"no","_backorders":"no","_sold_individually":"no","_weight":"3","_virtual":"no","_downloadable":"no","_download_limit":"-1","_download_expiry":"-1","_stock":"","_stock_status":"outofstock","_wc_average_rating":"0","_wc_review_count":"0","_product_version":"10.1.4","_price":"","shopengine_product_views_count":"3106","_thumbnail_id":"5125","_product_attributes":{"erscheinungsdatum":{"name":"Date de publication","value":"15.09.2013","position":0,"is_visible":1,"is_variation":0,"is_taxonomy":0,"checkout_visible":0}},"_nutrient_ids":[],"_upsell_ids":null,"pswc_subtitle":null,"_default_delivery_time":null,"_wp_desired_post_slug":null,"_isbn":null,"pageType":null,"isExternalUrl":null,"pageId":null,"externalUrl":null,"hideCookieBanner":null,"isTargetBlank":null,"isProviderCurrentWebsite":null,"isEmbeddingOnlyExternalResources":null,"legalBasis":null,"dataProcessingInCountries":null,"dataProcessingInCountriesSpecialTreatments":null,"technicalDefinitions":null,"googleConsentModeConsentTypes":null,"executePriority":null,"executeCodeOptInWhenNoTagManagerConsentIsGiven":null,"executeCodeOptOutWhenNoTagManagerConsentIsGiven":null,"deleteTechnicalDefinitionsAfterOptOut":null,"presetId":null,"presetVersion":null,"provider":null,"providerContactPhone":null,"providerContactEmail":null,"providerContactLink":null,"uniqueName":null,"providerPrivacyPolicyUrl":null,"providerLegalNoticeUrl":null,"codeOptIn":null,"codeOptOut":null,"codeOnPageLoad":null,"language_code":null,"shopengine_template__post_meta__type":null,"shopengine_template__post_meta":null,"shopengine_template__post_meta__edit_with":null,"origin":null,"_enabled":null,"_filters":null,"_layout":null,"_elementor_import_session_id":null,"_wp_trash_meta_status":null,"_wp_trash_meta_time":null,"_edit_lock":"1743345960:2","_elementor_floating_elements_type":null,"_elementor_edit_mode":null,"_elementor_template_type":null,"tc-thumb-fld":{"_thumb_id":5125,"_thumb_type":"thumb"},"_wp_page_template":"default","_elementor_version":null,"_elementor_pro_version":null,"_elementor_page_settings":null,"_elementor_data":null,"_elementor_conditions":null,"_elementor_popup_display_settings":null,"_edit_last":"2","_elementor_template_sub_type":null,"_elementor_controls_usage":null,"_elementor_screenshot":null,"_elementor_css":null,"_elementor_page_assets":[],"_elementor_element_cache":null,"_elementor_screenshot_failed":null,"_elementor_source":null,"_wp_old_date":null,"layout_key":"","post_slider_check_key":"0","_links":{"self":[{"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/product\/3710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/media\/5125"}],"wp:attachment":[{"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/media?parent=3710"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/product_brand?post=3710"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/product_cat?post=3710"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/snoeck.de\/fr\/wp-json\/wp\/v2\/product_tag?post=3710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}